{"id":6956,"count":21,"description":"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder. Unsere Klebeb\u00e4nder bieten den Extraschutz, den Sie f\u00fcr die letzten Windungen oder Formspule m\u00f6glicherweise w\u00fcnschen. Falls Sie Phasenisolierung ben\u00f6tigen, die an ihrem Platz bleibt, sind unsere haftenden Glasfaser-Gewebeb\u00e4nder eine hervorragende Wahl. Wenn Sie Kabelverbindungen haben und f\u00fcr den Splei\u00df zus\u00e4tzlichen Schutz m\u00f6chten, haben wir das Glas-Stoff- oder Laminatband, das Sie w\u00fcnschen. IPG ist der einzige Hersteller, der das passende Produkt hat, wenn Sie Kantenband f\u00fcr Slot-Liner m\u00f6chten.\u00a0 Wir fertigen auch Bandprodukte, um einen Formspulendrahtstapel zu Spulenb\u00fcndel von der Wickelmaschine abzunehmen und sicherzustellen, dass sie zuverl\u00e4ssig an ihrem Platz bleiben. Wenn es um eine \u201edritte Hand\u201c geht, um Dinge an ihrem Platz zu halten oder Spulen fester zu wickeln, oder wenn Sie besonders nichtleitende oder Hochtemperatur-B\u00e4nder brauchen, haben wir Produktl\u00f6sungen f\u00fcr Ihre Anwendung. Was druckempfindliche Isolierb\u00e4nder betrifft, k\u00fcmmert sich IPG um alles rund um den Generator.","link":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/","name":"Generatoren","slug":"generatoren-de","taxonomy":"associated_application","parent":6883,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Generatoren - IPG<\/title>\n<meta name=\"description\" content=\"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generatoren Archives\" \/>\n<meta property=\"og:description\" content=\"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/\" \/>\n<meta property=\"og:site_name\" content=\"IPG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IPGtape\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/de\\\/associated_application\\\/generatoren-de\\\/\",\"url\":\"https:\\\/\\\/www.itape.com\\\/de\\\/associated_application\\\/generatoren-de\\\/\",\"name\":\"Generatoren - IPG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/#website\"},\"description\":\"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/de\\\/associated_application\\\/generatoren-de\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/de\\\/associated_application\\\/generatoren-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itape.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elektro \\\/ Elektronik\",\"item\":\"https:\\\/\\\/www.itape.com\\\/de\\\/associated_application\\\/elektroelektronik-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Generatoren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/#website\",\"url\":\"https:\\\/\\\/www.itape.com\\\/\",\"name\":\"IPG\",\"description\":\"Global Leader in Packaging and Protective Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itape.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/#organization\",\"name\":\"IPG\",\"url\":\"https:\\\/\\\/www.itape.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IPG-logo-2.png\",\"contentUrl\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IPG-logo-2.png\",\"width\":60,\"height\":60,\"caption\":\"IPG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/intertape\",\"https:\\\/\\\/x.com\\\/IPGtape\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/intertape-polymer-group\",\"https:\\\/\\\/www.instagram.com\\\/ipgtape\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/IPGtape\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Generatoren - IPG","description":"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/","og_locale":"de_DE","og_type":"article","og_title":"Generatoren Archives","og_description":"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder.","og_url":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/","og_site_name":"IPG","twitter_card":"summary_large_image","twitter_site":"@IPGtape","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/","url":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/","name":"Generatoren - IPG","isPartOf":{"@id":"https:\/\/www.itape.com\/#website"},"description":"Generatoren erfordern ebenso wie Motoren ein komplettes Sortiment qualitativ hochwertiger, robuster und zuverl\u00e4ssiger druckempfindlicher Isolierb\u00e4nder.","breadcrumb":{"@id":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itape.com\/de\/associated_application\/generatoren-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itape.com\/de\/"},{"@type":"ListItem","position":2,"name":"Elektro \/ Elektronik","item":"https:\/\/www.itape.com\/de\/associated_application\/elektroelektronik-de\/"},{"@type":"ListItem","position":3,"name":"Generatoren"}]},{"@type":"WebSite","@id":"https:\/\/www.itape.com\/#website","url":"https:\/\/www.itape.com\/","name":"IPG","description":"Global Leader in Packaging and Protective Solutions","publisher":{"@id":"https:\/\/www.itape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.itape.com\/#organization","name":"IPG","url":"https:\/\/www.itape.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.itape.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.itape.com\/wp-content\/uploads\/2024\/06\/IPG-logo-2.png","contentUrl":"https:\/\/www.itape.com\/wp-content\/uploads\/2024\/06\/IPG-logo-2.png","width":60,"height":60,"caption":"IPG"},"image":{"@id":"https:\/\/www.itape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/intertape","https:\/\/x.com\/IPGtape","https:\/\/www.linkedin.com\/company\/intertape-polymer-group","https:\/\/www.instagram.com\/ipgtape","https:\/\/www.youtube.com\/user\/IPGtape"]}]}},"_links":{"self":[{"href":"https:\/\/www.itape.com\/de\/wp-json\/wp\/v2\/associated_application\/6956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itape.com\/de\/wp-json\/wp\/v2\/associated_application"}],"about":[{"href":"https:\/\/www.itape.com\/de\/wp-json\/wp\/v2\/taxonomies\/associated_application"}],"up":[{"embeddable":true,"href":"https:\/\/www.itape.com\/de\/wp-json\/wp\/v2\/associated_application\/6883"}],"wp:post_type":[{"href":"https:\/\/www.itape.com\/de\/wp-json\/wp\/v2\/product?associated_application=6956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}