{"id":48545,"date":"2023-01-12T14:35:28","date_gmt":"2023-01-12T14:35:28","guid":{"rendered":"https:\/\/www.itape.com\/product\/190-es\/"},"modified":"2023-04-10T14:25:03","modified_gmt":"2023-04-10T14:25:03","slug":"190-es","status":"publish","type":"product","link":"https:\/\/www.itape.com\/es\/product\/190-es\/","title":{"rendered":"190"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>INTENSIDAD ALTA. Usos recomendados: precintado de cajas de peso medio, incluidos contenedores ranurados comunes, de solapado completo, telesc\u00f3picos y otros. Funciona como sellador contra el polvo para su uso en planta. Precintado para cajas conformadas por unidades (pal\u00e9s). Empalme de papeles y embalaje de productos alimenticios. Embalaje ecol\u00f3gico. Util\u00edcela cuando no se requiera una cinta reforzada o alta resistencia. Disponible en color natural y blanco.<\/p>\n","protected":false},"featured_media":53457,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7376,7863,7897,8267,7844,7838],"product_tag":[7504,7504,8264],"associated_application":[7201,7261,7267,7938,7206,7202,7210,7292,7283,7203,7289,7299,7209,7216,7287],"class_list":{"0":"post-48545","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-water-activated-tape-es","7":"product_cat-carton-sealing-products-cinta-activada-por-agua-es","8":"product_cat-sustainable-packaging-cinta-activada-por-agua-es","9":"product_cat-cradle-to-cradle-products-es","10":"product_cat-sustainable-packaging-es","11":"product_cat-carton-sealing-products-es","12":"product_tag-central-reinforced-wat-es","14":"product_tag-cradle-to-cradle-certified-es","15":"associated_application-aeroespacial-es","16":"associated_application-automatizacion-del-precintado-es","17":"associated_application-cinta-imprimible-es","18":"associated_application-cintas-de-embalaje-es","19":"associated_application-comercio-electronico-es","20":"associated_application-dispositivos-es","21":"associated_application-fabricacion-general-es","22":"associated_application-marcado-es-fabricacion-general-es","23":"associated_application-marcado-es","24":"associated_application-mercado-de-recambios-de-automocion-es","25":"associated_application-precinto-de-seguridad-es-procesamiento-de-alimentos-es","26":"associated_application-precinto-de-seguridad-es-fabricacion-general-es","27":"associated_application-procesamiento-de-alimentos-es","28":"associated_application-transporte-es","29":"associated_application-transportealmacenamiento-refrigerado-es","31":"first","32":"instock","33":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.1 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>190 - IPG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itape.com\/es\/product\/190-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"190\" \/>\n<meta property=\"og:description\" content=\"INTENSIDAD ALTA. Usos recomendados: precintado de cajas de peso medio, incluidos contenedores ranurados comunes, de solapado completo, telesc\u00f3picos y otros. Funciona como sellador contra el polvo para su uso en planta. Precintado para cajas conformadas por unidades (pal\u00e9s). Empalme de papeles y embalaje de productos alimenticios. Embalaje ecol\u00f3gico. Util\u00edcela cuando no se requiera una cinta reforzada o alta resistencia. Disponible en color natural y blanco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itape.com\/es\/product\/190-es\/\" \/>\n<meta property=\"og:site_name\" content=\"IPG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intertape\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-10T14:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"2400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IPGtape\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/\",\"url\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/\",\"name\":\"190 - IPG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/190_high-1.jpg\",\"datePublished\":\"2023-01-12T14:35:28+00:00\",\"dateModified\":\"2023-04-10T14:25:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/190_high-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/190_high-1.jpg\",\"width\":2400,\"height\":2400,\"caption\":\"190_WAT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/es\\\/product\\\/190-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itape.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.itape.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"190\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/#website\",\"url\":\"https:\\\/\\\/www.itape.com\\\/\",\"name\":\"IPG\",\"description\":\"Global Leader in Packaging and Protective Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itape.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/#organization\",\"name\":\"IPG\",\"url\":\"https:\\\/\\\/www.itape.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itape.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IPG-logo-2.png\",\"contentUrl\":\"https:\\\/\\\/www.itape.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IPG-logo-2.png\",\"width\":60,\"height\":60,\"caption\":\"IPG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itape.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/intertape\",\"https:\\\/\\\/x.com\\\/IPGtape\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/intertape-polymer-group\",\"https:\\\/\\\/www.instagram.com\\\/ipgtape\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/IPGtape\"]}]}<\/script>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"fcc3aa51ddf4\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"190 - IPG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itape.com\/es\/product\/190-es\/","og_locale":"es_ES","og_type":"article","og_title":"190","og_description":"INTENSIDAD ALTA. Usos recomendados: precintado de cajas de peso medio, incluidos contenedores ranurados comunes, de solapado completo, telesc\u00f3picos y otros. Funciona como sellador contra el polvo para su uso en planta. Precintado para cajas conformadas por unidades (pal\u00e9s). Empalme de papeles y embalaje de productos alimenticios. Embalaje ecol\u00f3gico. Util\u00edcela cuando no se requiera una cinta reforzada o alta resistencia. Disponible en color natural y blanco.","og_url":"https:\/\/www.itape.com\/es\/product\/190-es\/","og_site_name":"IPG","article_publisher":"https:\/\/www.facebook.com\/intertape","article_modified_time":"2023-04-10T14:25:03+00:00","og_image":[{"width":2400,"height":2400,"url":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@IPGtape","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itape.com\/es\/product\/190-es\/","url":"https:\/\/www.itape.com\/es\/product\/190-es\/","name":"190 - IPG","isPartOf":{"@id":"https:\/\/www.itape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itape.com\/es\/product\/190-es\/#primaryimage"},"image":{"@id":"https:\/\/www.itape.com\/es\/product\/190-es\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg","datePublished":"2023-01-12T14:35:28+00:00","dateModified":"2023-04-10T14:25:03+00:00","breadcrumb":{"@id":"https:\/\/www.itape.com\/es\/product\/190-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itape.com\/es\/product\/190-es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itape.com\/es\/product\/190-es\/#primaryimage","url":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg","contentUrl":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg","width":2400,"height":2400,"caption":"190_WAT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itape.com\/es\/product\/190-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itape.com\/es\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.itape.com\/products\/"},{"@type":"ListItem","position":3,"name":"190"}]},{"@type":"WebSite","@id":"https:\/\/www.itape.com\/#website","url":"https:\/\/www.itape.com\/","name":"IPG","description":"Global Leader in Packaging and Protective Solutions","publisher":{"@id":"https:\/\/www.itape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itape.com\/#organization","name":"IPG","url":"https:\/\/www.itape.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itape.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.itape.com\/wp-content\/uploads\/2024\/06\/IPG-logo-2.png","contentUrl":"https:\/\/www.itape.com\/wp-content\/uploads\/2024\/06\/IPG-logo-2.png","width":60,"height":60,"caption":"IPG"},"image":{"@id":"https:\/\/www.itape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/intertape","https:\/\/x.com\/IPGtape","https:\/\/www.linkedin.com\/company\/intertape-polymer-group","https:\/\/www.instagram.com\/ipgtape","https:\/\/www.youtube.com\/user\/IPGtape"]}]},"product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"fcc3aa51ddf4","product_condition":"new"},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/itape.com\/es\/product\/190-es\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"190","url":"https:\/\/www.itape.com\/es\/product\/190-es\/","mainEntityOfPage":{"@type":"WebPage","@id":"https:\/\/www.itape.com\/es\/product\/190-es\/"},"thumbnailUrl":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg"},"articleSection":"Sin categorizar","author":[{"@type":"Person","name":"IPG"}],"creator":["IPG"],"publisher":{"@type":"Organization","name":"IPG","logo":"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/03\/IPG-logo-2.png"},"keywords":[],"dateCreated":"2023-01-12T14:35:28Z","datePublished":"2023-01-12T14:35:28Z","dateModified":"2023-04-10T14:25:03Z"},"rendered":"<meta name=\"parsely-title\" content=\"190\" \/>\n<meta name=\"parsely-link\" content=\"https:\/\/www.itape.com\/es\/product\/190-es\/\" \/>\n<meta name=\"parsely-type\" content=\"index\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/www.itape.com\/wp-content\/uploads\/2023\/01\/190_high-1.jpg?w=150&amp;h=150&amp;crop=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2023-01-12T14:35:28Z\" \/>\n<meta name=\"parsely-section\" content=\"Sin categorizar\" \/>\n<meta name=\"parsely-author\" content=\"IPG\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/itape.com\/p.js"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/product\/48545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/comments?post=48545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/media\/53457"}],"wp:attachment":[{"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/media?parent=48545"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/product_brand?post=48545"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/product_cat?post=48545"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/product_tag?post=48545"},{"taxonomy":"associated_application","embeddable":true,"href":"https:\/\/www.itape.com\/es\/wp-json\/wp\/v2\/associated_application?post=48545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}